{"id":1961,"date":"2018-10-12T18:57:01","date_gmt":"2018-10-12T18:57:01","guid":{"rendered":"https:\/\/logient.com\/?p=1961"},"modified":"2021-02-01T17:34:52","modified_gmt":"2021-02-01T17:34:52","slug":"lt-plus-est-officiellement-lancee","status":"publish","type":"post","link":"https:\/\/logient.com\/fr\/lt-plus-est-officiellement-lancee\/","title":{"rendered":"LT Plus est officiellement lanc\u00e9e"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>LT Plus prend en charge la mise \u00e0 niveau des comp\u00e9tences des employ\u00e9s, met sur pied des \u00e9quipes de d\u00e9veloppement aguerries ou a recours \u00e0 des m\u00e9thodologies reconnues ainsi qu\u2019aux meilleures pratiques de l\u2019industrie.<\/p>\n","protected":false},"author":12,"featured_media":3276,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"1909,2124,2275,2159,1809,1879","_relevanssi_noindex_reason":"","inline_featured_image":false,"mc4wp_mailchimp_campaign":[],"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-1961","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vie-dentreprise"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>LT Plus est officiellement lanc\u00e9e - Logient<\/title>\n<meta name=\"description\" content=\"Soucieuse d\u2019offrir les meilleurs services d\u2019impartition TI, Logient se dote de la division LT Plus pour la mise \u00e0 niveau des comp\u00e9tences des employ\u00e9s.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/logient.com\/fr\/lt-plus-est-officiellement-lancee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LT Plus est officiellement lanc\u00e9e - Logient\" \/>\n<meta property=\"og:description\" content=\"Soucieuse d\u2019offrir les meilleurs services d\u2019impartition TI, Logient se dote de la division LT Plus pour la mise \u00e0 niveau des comp\u00e9tences des employ\u00e9s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/logient.com\/fr\/lt-plus-est-officiellement-lancee\/\" \/>\n<meta property=\"og:site_name\" content=\"Logient\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-12T18:57:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-01T17:34:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/logient.com\/app\/uploads\/2018\/10\/logient-ltplus-recrutement-impartition-ti.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2076\" \/>\n\t<meta property=\"og:image:height\" content=\"1424\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Laurence Trudeau\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Laurence Trudeau\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/logient.com\/fr\/lt-plus-est-officiellement-lancee\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/logient.com\/fr\/lt-plus-est-officiellement-lancee\/\"},\"author\":{\"name\":\"Laurence Trudeau\",\"@id\":\"https:\/\/logient.com\/fr\/#\/schema\/person\/f524289c6e7e3ab1e39aaded48536dcc\"},\"headline\":\"LT Plus est officiellement lanc\u00e9e\",\"datePublished\":\"2018-10-12T18:57:01+00:00\",\"dateModified\":\"2021-02-01T17:34:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/logient.com\/fr\/lt-plus-est-officiellement-lancee\/\"},\"wordCount\":6,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/logient.com\/fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/logient.com\/fr\/lt-plus-est-officiellement-lancee\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/logient.com\/app\/uploads\/2018\/10\/logient-ltplus-recrutement-impartition-ti.jpg\",\"articleSection\":[\"Vie d'entreprise\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/logient.com\/fr\/lt-plus-est-officiellement-lancee\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/logient.com\/fr\/lt-plus-est-officiellement-lancee\/\",\"url\":\"https:\/\/logient.com\/fr\/lt-plus-est-officiellement-lancee\/\",\"name\":\"LT Plus est officiellement lanc\u00e9e - Logient\",\"isPartOf\":{\"@id\":\"https:\/\/logient.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/logient.com\/fr\/lt-plus-est-officiellement-lancee\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/logient.com\/fr\/lt-plus-est-officiellement-lancee\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/logient.com\/app\/uploads\/2018\/10\/logient-ltplus-recrutement-impartition-ti.jpg\",\"datePublished\":\"2018-10-12T18:57:01+00:00\",\"dateModified\":\"2021-02-01T17:34:52+00:00\",\"description\":\"Soucieuse d\u2019offrir les meilleurs services d\u2019impartition TI, Logient se dote de la division LT Plus pour la mise \u00e0 niveau des comp\u00e9tences des employ\u00e9s.\",\"breadcrumb\":{\"@id\":\"https:\/\/logient.com\/fr\/lt-plus-est-officiellement-lancee\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/logient.com\/fr\/lt-plus-est-officiellement-lancee\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/logient.com\/fr\/lt-plus-est-officiellement-lancee\/#primaryimage\",\"url\":\"https:\/\/logient.com\/app\/uploads\/2018\/10\/logient-ltplus-recrutement-impartition-ti.jpg\",\"contentUrl\":\"https:\/\/logient.com\/app\/uploads\/2018\/10\/logient-ltplus-recrutement-impartition-ti.jpg\",\"width\":2076,\"height\":1424},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/logient.com\/fr\/lt-plus-est-officiellement-lancee\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/logient.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LT Plus est officiellement lanc\u00e9e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/logient.com\/fr\/#website\",\"url\":\"https:\/\/logient.com\/fr\/\",\"name\":\"Logient\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/logient.com\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/logient.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/logient.com\/fr\/#organization\",\"name\":\"Logient\",\"url\":\"https:\/\/logient.com\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/logient.com\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/logient.com\/app\/uploads\/2023\/09\/group-53-1-scaled-1.jpg\",\"contentUrl\":\"https:\/\/logient.com\/app\/uploads\/2023\/09\/group-53-1-scaled-1.jpg\",\"width\":2560,\"height\":1797,\"caption\":\"Logient\"},\"image\":{\"@id\":\"https:\/\/logient.com\/fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/logient.com\/fr\/#\/schema\/person\/f524289c6e7e3ab1e39aaded48536dcc\",\"name\":\"Laurence Trudeau\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/logient.com\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/be125d407d16e8c91a8e0d8ab070a53fd84a8477dfbf953c8be8b7ed9b0c362f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/be125d407d16e8c91a8e0d8ab070a53fd84a8477dfbf953c8be8b7ed9b0c362f?s=96&d=mm&r=g\",\"caption\":\"Laurence Trudeau\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LT Plus est officiellement lanc\u00e9e - Logient","description":"Soucieuse d\u2019offrir les meilleurs services d\u2019impartition TI, Logient se dote de la division LT Plus pour la mise \u00e0 niveau des comp\u00e9tences des employ\u00e9s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/logient.com\/fr\/lt-plus-est-officiellement-lancee\/","og_locale":"fr_FR","og_type":"article","og_title":"LT Plus est officiellement lanc\u00e9e - Logient","og_description":"Soucieuse d\u2019offrir les meilleurs services d\u2019impartition TI, Logient se dote de la division LT Plus pour la mise \u00e0 niveau des comp\u00e9tences des employ\u00e9s.","og_url":"https:\/\/logient.com\/fr\/lt-plus-est-officiellement-lancee\/","og_site_name":"Logient","article_published_time":"2018-10-12T18:57:01+00:00","article_modified_time":"2021-02-01T17:34:52+00:00","og_image":[{"width":2076,"height":1424,"url":"https:\/\/logient.com\/app\/uploads\/2018\/10\/logient-ltplus-recrutement-impartition-ti.jpg","type":"image\/jpeg"}],"author":"Laurence Trudeau","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Laurence Trudeau"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/logient.com\/fr\/lt-plus-est-officiellement-lancee\/#article","isPartOf":{"@id":"https:\/\/logient.com\/fr\/lt-plus-est-officiellement-lancee\/"},"author":{"name":"Laurence Trudeau","@id":"https:\/\/logient.com\/fr\/#\/schema\/person\/f524289c6e7e3ab1e39aaded48536dcc"},"headline":"LT Plus est officiellement lanc\u00e9e","datePublished":"2018-10-12T18:57:01+00:00","dateModified":"2021-02-01T17:34:52+00:00","mainEntityOfPage":{"@id":"https:\/\/logient.com\/fr\/lt-plus-est-officiellement-lancee\/"},"wordCount":6,"commentCount":0,"publisher":{"@id":"https:\/\/logient.com\/fr\/#organization"},"image":{"@id":"https:\/\/logient.com\/fr\/lt-plus-est-officiellement-lancee\/#primaryimage"},"thumbnailUrl":"https:\/\/logient.com\/app\/uploads\/2018\/10\/logient-ltplus-recrutement-impartition-ti.jpg","articleSection":["Vie d'entreprise"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/logient.com\/fr\/lt-plus-est-officiellement-lancee\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/logient.com\/fr\/lt-plus-est-officiellement-lancee\/","url":"https:\/\/logient.com\/fr\/lt-plus-est-officiellement-lancee\/","name":"LT Plus est officiellement lanc\u00e9e - Logient","isPartOf":{"@id":"https:\/\/logient.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/logient.com\/fr\/lt-plus-est-officiellement-lancee\/#primaryimage"},"image":{"@id":"https:\/\/logient.com\/fr\/lt-plus-est-officiellement-lancee\/#primaryimage"},"thumbnailUrl":"https:\/\/logient.com\/app\/uploads\/2018\/10\/logient-ltplus-recrutement-impartition-ti.jpg","datePublished":"2018-10-12T18:57:01+00:00","dateModified":"2021-02-01T17:34:52+00:00","description":"Soucieuse d\u2019offrir les meilleurs services d\u2019impartition TI, Logient se dote de la division LT Plus pour la mise \u00e0 niveau des comp\u00e9tences des employ\u00e9s.","breadcrumb":{"@id":"https:\/\/logient.com\/fr\/lt-plus-est-officiellement-lancee\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/logient.com\/fr\/lt-plus-est-officiellement-lancee\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/logient.com\/fr\/lt-plus-est-officiellement-lancee\/#primaryimage","url":"https:\/\/logient.com\/app\/uploads\/2018\/10\/logient-ltplus-recrutement-impartition-ti.jpg","contentUrl":"https:\/\/logient.com\/app\/uploads\/2018\/10\/logient-ltplus-recrutement-impartition-ti.jpg","width":2076,"height":1424},{"@type":"BreadcrumbList","@id":"https:\/\/logient.com\/fr\/lt-plus-est-officiellement-lancee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/logient.com\/fr\/"},{"@type":"ListItem","position":2,"name":"LT Plus est officiellement lanc\u00e9e"}]},{"@type":"WebSite","@id":"https:\/\/logient.com\/fr\/#website","url":"https:\/\/logient.com\/fr\/","name":"Logient","description":"","publisher":{"@id":"https:\/\/logient.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/logient.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/logient.com\/fr\/#organization","name":"Logient","url":"https:\/\/logient.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/logient.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/logient.com\/app\/uploads\/2023\/09\/group-53-1-scaled-1.jpg","contentUrl":"https:\/\/logient.com\/app\/uploads\/2023\/09\/group-53-1-scaled-1.jpg","width":2560,"height":1797,"caption":"Logient"},"image":{"@id":"https:\/\/logient.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/logient.com\/fr\/#\/schema\/person\/f524289c6e7e3ab1e39aaded48536dcc","name":"Laurence Trudeau","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/logient.com\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/be125d407d16e8c91a8e0d8ab070a53fd84a8477dfbf953c8be8b7ed9b0c362f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/be125d407d16e8c91a8e0d8ab070a53fd84a8477dfbf953c8be8b7ed9b0c362f?s=96&d=mm&r=g","caption":"Laurence Trudeau"}}]}},"jetpack_featured_media_url":"https:\/\/logient.com\/app\/uploads\/2018\/10\/logient-ltplus-recrutement-impartition-ti.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/logient.com\/fr\/wp-json\/wp\/v2\/posts\/1961","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/logient.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/logient.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/logient.com\/fr\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/logient.com\/fr\/wp-json\/wp\/v2\/comments?post=1961"}],"version-history":[{"count":0,"href":"https:\/\/logient.com\/fr\/wp-json\/wp\/v2\/posts\/1961\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/logient.com\/fr\/wp-json\/wp\/v2\/media\/3276"}],"wp:attachment":[{"href":"https:\/\/logient.com\/fr\/wp-json\/wp\/v2\/media?parent=1961"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/logient.com\/fr\/wp-json\/wp\/v2\/categories?post=1961"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/logient.com\/fr\/wp-json\/wp\/v2\/tags?post=1961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}